{"id":63,"count":5,"description":"","link":"https:\/\/clients.perceptivmedia.com.au\/marco-polo\/product-category\/spreads\/","name":"Spreads","slug":"spreads","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/clients.perceptivmedia.com.au\/marco-polo\/wp-json\/wp\/v2\/product_cat\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clients.perceptivmedia.com.au\/marco-polo\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/clients.perceptivmedia.com.au\/marco-polo\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/clients.perceptivmedia.com.au\/marco-polo\/wp-json\/wp\/v2\/product?product_cat=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}